{"id":4944,"date":"2016-03-04T10:49:55","date_gmt":"2016-03-04T09:49:55","guid":{"rendered":"https:\/\/www.parruccheonline.com\/prodotto\/default-category\/protesi-capelli\/protesi-capelli-uomo\/protesi-capelli-farcap-5-riccio\/"},"modified":"2025-05-22T06:14:57","modified_gmt":"2025-05-22T04:14:57","slug":"protesi-capelli-farcap-5-riccio","status":"publish","type":"product","link":"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/","title":{"rendered":"Protesi capelli Farcap 5 riccio"},"content":{"rendered":"<p><strong>Protesi capelli Farcap 5<\/strong> l&#8217;ultima produzione per coloro che amano la traspirazione e un prodotto leggero da indossare. la misura \u00e8 di cm cm 23 x 19 e modificabile fino a cm 20 x 11.<\/p>\n<p><strong>Protesi capillare<\/strong> interamente lavorata a mano con un bordo in poli leggero tutto perimetralmente di 5 cm. e un lace svizzero centrale per la traspirazione, il quale fornisce un ottimale effetto pelle.<\/p>\n<p>Avvertenza: la Protesi pu\u00f2 contenere una piccola quantit\u00e0 di capelli in fibra sintetica o talvolta di yak, funzionali all&#8217;ottimale realizzazione del prodotto.<\/p>\n<p><!-- START: massdescriptionedit --><\/p>\n<p><a href=\"http:\/\/farcaphair.com\/wp-content\/uploads\/2016\/03\/protesi-capelli-PER-MAIL-3.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\" size-full wp-image-317\" src=\"https:\/\/www.parruccheonline.com\/wp-content\/uploads\/2011\/03\/catalogo-protesi-capelli.jpg\" alt=\"catalogo protesi capelli\" width=\"150\" height=\"208\" \/><\/a>\u00a0\u00a0\u00a0\u00a0 <a href=\"http:\/\/www.parruccheonline.com\/content\/14-protesi-capelli\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-318 size-full wp-image-319\" src=\"https:\/\/www.parruccheonline.com\/wp-content\/uploads\/2011\/03\/MANUTENZIONE-PROTESI-CAPELLI.jpg\" alt=\"protesi capelli forum\" width=\"275\" height=\"183\" srcset=\"https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2011\/03\/MANUTENZIONE-PROTESI-CAPELLI.jpg 525w, https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2011\/03\/MANUTENZIONE-PROTESI-CAPELLI-300x200.jpg 300w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>\u00a0\u00a0\u00a0\u00a0 <img decoding=\"async\" src=\"https:\/\/www.parruccheonline.com\/wp-content\/uploads\/2011\/03\/MANUTENZIONE-PROTESI-CAPELLI_1.jpg\" alt=\"accessori\" width=\"275\" height=\"183\" \/><\/a><\/p>\n<p><!-- END: massdescriptionedit --><!-- START: massdescriptionedit --><!-- END: massdescriptionedit --><!-- START: massdescriptionedit --><\/p>\n<p><!-- END: massdescriptionedit --><!-- START: massdescriptionedit --><\/p>\n<p><!-- END: massdescriptionedit --><!-- START: massdescriptionedit --><\/p>\n<p><!-- END: massdescriptionedit --><\/p>\n","protected":false},"excerpt":{"rendered":"<p><!-- START: massdescriptionedit --><!-- END: massdescriptionedit --><\/p>\n<p><strong>Protesi capelli Farcap 5 <\/strong>riccio\/mosso di capelli cm 23&#215;19<strong>\u00a0<\/strong> l&#8217;ultima produzione per coloro che amano la traspirazione e un prodotto leggero da indossare. la misura \u00e8 di cm 23&#215;19 e modificabile fino a cm 20&#215;11<\/p>\n<p><!-- START: massdescriptionedit --><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-320\" src=\"https:\/\/www.parruccheonline.com\/wp-content\/uploads\/2011\/03\/spedizioni-immediate.jpg\" alt=\"\" width=\"137\" height=\"85\" srcset=\"https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2011\/03\/spedizioni-immediate.jpg 881w, https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2011\/03\/spedizioni-immediate-800x495.jpg 800w, https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2011\/03\/spedizioni-immediate-300x186.jpg 300w, https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2011\/03\/spedizioni-immediate-768x475.jpg 768w\" sizes=\"(max-width: 137px) 100vw, 137px\" \/><\/p>\n<p><!-- END: massdescriptionedit --><\/p>\n","protected":false},"featured_media":4940,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[1558,1617,1571],"product_tag":[1901,1626,1792,1772],"class_list":{"0":"post-4944","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-protesi-capelli-uomo","7":"product_cat-protesi-capelli","8":"product_cat-impianti-capillari-standard","9":"product_tag-farcap-5","10":"product_tag-protesi-capelli","11":"product_tag-protesi-capelli-online","12":"product_tag-protesi-capillari","13":"pa_featured-no","14":"pa_fefa_impianti_capillari-biondoscuro","15":"pa_fefa_impianti_capillari-castano","16":"pa_fefa_impianti_capillari-castanochiaro","17":"pa_fefa_impianti_capillari-castanocon80digrigio","18":"pa_fefa_impianti_capillari-castanomediocon20digrigio","19":"pa_fefa_impianti_capillari-castanoscuro","20":"pa_fefa_impianti_capillari-castanoscurocon10digrigio","21":"pa_fefa_impianti_capillari-castanoscurocon20digrigio","22":"pa_fefa_impianti_capillari-castanoscurocon30digrigio","23":"pa_fefa_impianti_capillari-castanoscurocon50digrigio","24":"pa_fefa_impianti_capillari-nero1b","25":"pa_lavorazione_protesi-poliperimetraleelacecentrale","26":"pa_misura_calotta_protesi-cm23x19","27":"pa_protesi_capelli_riducibile-si","28":"pa_tipologia_capelli-naturaleremy","30":"first","31":"instock","32":"sale","33":"taxable","34":"shipping-taxable","35":"purchasable","36":"product-type-variable","swatches":"rey-swatches","show_selected":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.8 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Protesi capelli Farcap 5 riccio- ParruccheOnline.com<\/title>\n<meta name=\"description\" content=\"Protesi capelli Farcap 5 capelli ricci un mix di leggerezza e traspirazione assemblate in un unico prodotto, protesi di capelli Farcap 5. Spedizione immediata\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protesi capelli Farcap 5 riccio\" \/>\n<meta property=\"og:description\" content=\"Protesi capelli Farcap 5 capelli ricci un mix di leggerezza e traspirazione assemblate in un unico prodotto, protesi di capelli Farcap 5. Spedizione immediata\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/\" \/>\n<meta property=\"og:site_name\" content=\"Parrucche Online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/farcaphair\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-22T04:14:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2016\/03\/4850.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"561\" \/>\n\t<meta property=\"og:image:height\" content=\"856\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/\",\"url\":\"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/\",\"name\":\"Protesi capelli Farcap 5 riccio- ParruccheOnline.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.parruccheonline.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2016\/03\/4850.jpg\",\"datePublished\":\"2016-03-04T09:49:55+00:00\",\"dateModified\":\"2025-05-22T04:14:57+00:00\",\"description\":\"Protesi capelli Farcap 5 capelli ricci un mix di leggerezza e traspirazione assemblate in un unico prodotto, protesi di capelli Farcap 5. Spedizione immediata\",\"breadcrumb\":{\"@id\":\"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/#primaryimage\",\"url\":\"https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2016\/03\/4850.jpg\",\"contentUrl\":\"https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2016\/03\/4850.jpg\",\"width\":561,\"height\":856,\"caption\":\"Protesi capelli Farcap 5 riccio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.parruccheonline.com\/stagingg\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.parruccheonline.com\/stagingg\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Protesi capelli Farcap 5 riccio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.parruccheonline.com\/#website\",\"url\":\"https:\/\/www.parruccheonline.com\/\",\"name\":\"Parrucche Online\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.parruccheonline.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.parruccheonline.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.parruccheonline.com\/#organization\",\"name\":\"Parrucche Online\",\"url\":\"https:\/\/www.parruccheonline.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.parruccheonline.com\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2024\/11\/logo_parrucche-online_nero.svg\",\"contentUrl\":\"http:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2024\/11\/logo_parrucche-online_nero.svg\",\"width\":1000,\"height\":280,\"caption\":\"Parrucche Online\"},\"image\":{\"@id\":\"https:\/\/www.parruccheonline.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/farcaphair\",\"https:\/\/www.instagram.com\/parrucche_online_official\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Protesi capelli Farcap 5 riccio- ParruccheOnline.com","description":"Protesi capelli Farcap 5 capelli ricci un mix di leggerezza e traspirazione assemblate in un unico prodotto, protesi di capelli Farcap 5. Spedizione immediata","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Protesi capelli Farcap 5 riccio","og_description":"Protesi capelli Farcap 5 capelli ricci un mix di leggerezza e traspirazione assemblate in un unico prodotto, protesi di capelli Farcap 5. Spedizione immediata","og_url":"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/","og_site_name":"Parrucche Online","article_publisher":"https:\/\/www.facebook.com\/farcaphair","article_modified_time":"2025-05-22T04:14:57+00:00","og_image":[{"width":561,"height":856,"url":"https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2016\/03\/4850.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/","url":"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/","name":"Protesi capelli Farcap 5 riccio- ParruccheOnline.com","isPartOf":{"@id":"https:\/\/www.parruccheonline.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/#primaryimage"},"image":{"@id":"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2016\/03\/4850.jpg","datePublished":"2016-03-04T09:49:55+00:00","dateModified":"2025-05-22T04:14:57+00:00","description":"Protesi capelli Farcap 5 capelli ricci un mix di leggerezza e traspirazione assemblate in un unico prodotto, protesi di capelli Farcap 5. Spedizione immediata","breadcrumb":{"@id":"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/#primaryimage","url":"https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2016\/03\/4850.jpg","contentUrl":"https:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2016\/03\/4850.jpg","width":561,"height":856,"caption":"Protesi capelli Farcap 5 riccio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.parruccheonline.com\/stagingg\/protesi-capelli-farcap-5-riccio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.parruccheonline.com\/stagingg\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.parruccheonline.com\/stagingg\/shop\/"},{"@type":"ListItem","position":3,"name":"Protesi capelli Farcap 5 riccio"}]},{"@type":"WebSite","@id":"https:\/\/www.parruccheonline.com\/#website","url":"https:\/\/www.parruccheonline.com\/","name":"Parrucche Online","description":"","publisher":{"@id":"https:\/\/www.parruccheonline.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.parruccheonline.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.parruccheonline.com\/#organization","name":"Parrucche Online","url":"https:\/\/www.parruccheonline.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.parruccheonline.com\/#\/schema\/logo\/image\/","url":"http:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2024\/11\/logo_parrucche-online_nero.svg","contentUrl":"http:\/\/www.parruccheonline.com\/stagingg\/wp-content\/uploads\/2024\/11\/logo_parrucche-online_nero.svg","width":1000,"height":280,"caption":"Parrucche Online"},"image":{"@id":"https:\/\/www.parruccheonline.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/farcaphair","https:\/\/www.instagram.com\/parrucche_online_official\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.parruccheonline.com\/stagingg\/wp-json\/wp\/v2\/product\/4944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parruccheonline.com\/stagingg\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.parruccheonline.com\/stagingg\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.parruccheonline.com\/stagingg\/wp-json\/wp\/v2\/comments?post=4944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.parruccheonline.com\/stagingg\/wp-json\/wp\/v2\/media\/4940"}],"wp:attachment":[{"href":"https:\/\/www.parruccheonline.com\/stagingg\/wp-json\/wp\/v2\/media?parent=4944"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.parruccheonline.com\/stagingg\/wp-json\/wp\/v2\/product_cat?post=4944"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.parruccheonline.com\/stagingg\/wp-json\/wp\/v2\/product_tag?post=4944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}